{"id":3891,"date":"2020-12-02T11:54:42","date_gmt":"2020-12-02T10:54:42","guid":{"rendered":"https:\/\/www.heibel-unplugged.de\/?p=3891"},"modified":"2022-02-09T10:20:25","modified_gmt":"2022-02-09T09:20:25","slug":"so-tickt-die-boerse-totgesagte-leben-laenger-auferstehung-der-autoindustrie","status":"publish","type":"post","link":"https:\/\/www.heibel-ticker.de\/blog\/so-tickt-die-boerse-totgesagte-leben-laenger-auferstehung-der-autoindustrie\/","title":{"rendered":"So tickt die B\u00f6rse: Totgesagte leben l\u00e4nger, Auferstehung der Autoindustrie"},"content":{"rendered":"\n<p>Es war eine Sache von Monaten, dass Tesla im Wert an Renault, FiatChrysler, dann an Ford und General Motors sowie auch an Volkswagen, Daimler und BMW vorbei zog, schlie\u00dflich wurde auch Toyota \u00fcberholt und Tesla wurde in diesem Sommer zum wertvollsten Automobilkonzern der Welt. Heute k\u00f6nnen sie den Wert aller aufgez\u00e4hlten Autokonzerne zusammenwerfen, denn Tesla ist inzwischen wertvoller als alle anderen zusammen.<\/p>\n\n\n\n<p>Im Heibel-Ticker habe ich mich niemals auf die Diskussion eingelassen, ob der Elektroantrieb den Verbrennermotor vollst\u00e4ndig abl\u00f6sen wird. Auch die Diskussion, was nun letztlich tats\u00e4chlich umweltfreundlicher ist, wenn man den gesamten Lebenszyklus betrachtet, ist f\u00fcr uns als Anleger m\u00fc\u00dfig. F\u00fcr mich galt nur eins: Der Elektroantrieb macht die Luft in den Innenst\u00e4dten sauberer. Und in unserer Industriegesellschaft leben die meisten Menschen in St\u00e4dten, w\u00fcnschen sich also eine L\u00f6sung f\u00fcr die Innenst\u00e4dte und w\u00e4hlen entsprechend.<\/p>\n\n\n\n<p>Tesla-Gr\u00fcnder Elon Musk ist inzwischen zum zweitreichsten Menschen der Welt aufgestiegen, nur Amazon-Gr\u00fcnder Jeff Bezos ist reicher, Bill Gates, Mark Zuckerberg und Warren Buffet hat er jedoch \u00fcberholt. Man sollte meinen, die herk\u00f6mmlichen Autobauer sind dem Untergang geweiht. Denn die hier gezeigten Zahlen beweisen ja eindeutig, dass Tesla die ganze Welt erobert und f\u00fcr eine Nummer Zwei ist da kein Platz mehr, oder?<\/p>\n\n\n\n<p>Nun, genau das ist der Zeitpunkt, zu dem die totgesagte Autoindustrie wieder auferstehen k\u00f6nnte. Daimler und BMW haben \u00fcbrigens letzte Woche neue Jahreshochs erklommen.<\/p>\n\n\n\n<p>ThyssenKrupp und Salzgitter, die den Stahl f\u00fcr die Autos unserer deutschen Hersteller liefern, sprangen letzte Woche um 11% bzw. 17% resp. an. Auch der Stahlh\u00e4ndler Kl\u00f6ckner konnte um 13% zulegen. D\u00fcrr, Anbieter von Auto-Fertigungsstra\u00dfen, sprang um 13% an. Autozulieferer Sch\u00e4ffler konnte um 9% zulegen.<\/p>\n\n\n\n<p>Siltronic, Hersteller von Waffeln, die der Chipindustrie als Grundlage dienen, schoss um 14% in die H\u00f6he. Siltronics Kunden sind zu einem gro\u00dfen Teil Autozulieferer, die sich um die Bordelektronik k\u00fcmmern. Lanxess, Chemieproduzent von Spezial-Kunststoffen, die auch beim Autobau Eingang finden, konnte 9% zulegen.<\/p>\n\n\n\n<p>So konnte die Rohstoffbranche letzte Woche um durchschnittlich 7,7% ansteigen, die Automobilbranche um 3,3% und die Chemie um 3,1%.<\/p>\n\n\n\n<p>Der Grund? Ganz einfach: Autos werden derzeit f\u00fcr China produziert, dort ist Corona kein Thema mehr. Au\u00dferdem ist die Autoindustrie von der Verl\u00e4ngerung des Teil-Lockdowns nicht besonders hart betroffen.<\/p>\n\n\n\n<p>Ganz anders sieht es im Einzelhandel aus, der letzte Woche um 0,2% nachgab. Das Weihnachtsgesch\u00e4ft, mit dem sich viele Einzelh\u00e4ndler aus dem katastrophalen Corona-Jahr retten wollten, ist gestrichen worden.<\/p>\n\n\n\n<p>Die Rotation setzt sich fort: Anleger suchen nach Themen, die im Jahr 2021 funktionieren. Dabei wird gleichzeitig auch darauf geachtet, wie stark der aktuelle Lockdown zwischenzeitlich noch Schaden anrichten kann. W\u00e4hrend also der DAX letzte Woche nur moderat angestiegen ist, findet unter der Haube eine Rotation statt, die teilweise zu starken Kursspr\u00fcngen f\u00fchrt.<\/p>\n\n\n\n<p>Ja, Kursspr\u00fcngen: Es hat den Anschein, dass sich Aktien derzeit nur darin unterscheiden, wie stark sie steigen. Minuszeichen sind selten geworden. Durch das Licht am Ende des Tunnels, den Impfstoff, wird nun viel Kapital in den Aktienmarkt geschaufelt. Gewinnmitnahmen oder gar Panikverk\u00e4ufe scheint es nicht zu geben, es gibt lediglich eine Suche nach den besten Schn\u00e4ppchen.<\/p>\n\n\n\n<p>Meine komplette neue B\u00f6rsenbrief Ausgabe mit folgenden Themen finden Sie unter\u00a0<a href=\"https:\/\/www.heibel-ticker.de\/empfehlung?id=40&amp;refID=9\" target=\"_blank\" aria-label=\"www.heibel-ticker.de (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">www.heibel-ticker.de<\/a>:<\/p>\n\n\n\n<p>01.\u00a0 \u00a0 Info-Kicker: Ruhige Thanksgiving-Woche<br \/>02.\u00a0 \u00a0 So tickt die B\u00f6rse: Totgesagte leben l\u00e4nger<br \/>\u00a0 \u00a0 \u00a0 &#8211; TUI und Medios stellen alles in den Schatten<br \/>\u00a0 \u00a0 \u00a0 &#8211; Wochenperformance der wichtigsten Indizes<br \/>03.\u00a0 \u00a0 Sentiment: Positive Grundstimmung unterst\u00fctzt Aktienmarkt auf hohem Niveau<br \/>04.\u00a0 \u00a0 Ausblick: Crack-up Boom<br \/>\u00a0 \u00a0 \u00a0 &#8211; Zyklische Nach-Corona Aktien<br \/>\u00a0 \u00a0 \u00a0 &#8211; Corona-Aktien, die auch nach Corona attraktiv bleiben<br \/>\u00a0 \u00a0 \u00a0 &#8211; Bitte: Disziplin<br \/>05.\u00a0 \u00a0 Update beobachteter Werte: Medios, Wheaton Precious Metals<br \/>\u00a0 \u00a0 \u00a0 &#8211; Medios: Expansion beschleunigt, Aktie +20%<br \/>\u00a0 \u00a0 \u00a0 &#8211; Wheaton Precious Metals: Nochmals nachkaufen, \u00dcberposition schaffen<br \/>06.\u00a0 \u00a0 \u00dcbersicht HT-Portfolio\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<form class=\"new_abo\" style=\"margin: 0px;\" action=\"https:\/\/www.heibel-ticker.de\/abo\" method=\"post\">\n<h2 class=\"sgny-widget-title\"><font color=\"blue\">\u00dcber 25.000 Leser vertrauen dem Heibel-Ticker<\/font><\/h2>\n<br \/>\n<div class=\"mc4wp-form-fields\">Seit 1998 verfolge ich begeistert die B\u00f6rsen der USA und Europas. Mittlerweile schreibe ich w\u00f6chentlich f\u00fcr mehr als 25.000 Leser \u00fcber Hintergr\u00fcnde zum Aktienmarkt und Ursachen f\u00fcr Kursbewegungen von Aktien.<br \/>\n<br \/>\nMeine Leser sch\u00e4tzen meine neutrale, vereinfachende und unterhaltsame Art. Als Privatanleger nutzen sie meine Einsch\u00e4tzungen und Investmentideen zur selbstst\u00e4ndigen Portfolio-Optimierung.<br \/>\n<br \/>\nSie k\u00f6nnen sich zum <a href=\"https:\/\/www.heibel-ticker.de\/empfehlung?id=40&amp;refID=9\">Heibel-Ticker B\u00f6rsenbrief<\/a> gratis anmelden und erhalten jeden Freitag die neue Ausgabe direkt in Ihr Mail-Postfach.<br \/>\n<br \/>\nKein Spam, kein Abo, Abmeldung jederzeit m\u00f6glich.\n<\/div><br \/>\n<input name=\"refID\" type=\"hidden\" value=\"9\"\/>\n<input name=\"abo[subscribe]\" type=\"hidden\" value=\"subscribe\"\/><input id=\"input_email\" class=\"input_s\" name=\"abo[email]\" size=\"8\" type=\"text\" value=\"\" placeholder=\"E-Mail\"\/><br \/>\n<br \/>\n<input name=\"dsa\" required=\"\" type=\"checkbox\"\/> Ja, ich stimme der <a href=\"https:\/\/www.heibel-ticker.de\/static\/privacy\" target=\"_blank\" rel=\"noopener\">Datenschutzerkl\u00e4rung<\/a> des Heibel-Ticker B\u00f6rsenbriefes zu.<br \/>\n<br \/>\n<input class=\"sgny-readmore-btn send-btn\" name=\"sent2\" type=\"submit\" value=\"Kostenlos anmelden\"\/>\n<p class=\"info-txt\"><\/p>\n<\/form>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es war eine Sache von Monaten, dass Tesla im Wert an Renault, FiatChrysler, dann an Ford und General Motors sowie auch an Volkswagen, Daimler und BMW vorbei zog, schlie\u00dflich wurde auch Toyota \u00fcberholt und Tesla wurde in diesem Sommer zum wertvollsten Automobilkonzern der Welt. Heute k\u00f6nnen sie den Wert aller aufgez\u00e4hlten Autokonzerne zusammenwerfen, denn Tesla [&hellip;]<\/p>\n","protected":false},"author":7675,"featured_media":3892,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-markteinschatzung"],"_links":{"self":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/users\/7675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/comments?post=3891"}],"version-history":[{"count":1,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3891\/revisions"}],"predecessor-version":[{"id":3893,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3891\/revisions\/3893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media\/3892"}],"wp:attachment":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media?parent=3891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/categories?post=3891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/tags?post=3891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}