{"id":3907,"date":"2020-12-17T12:38:12","date_gmt":"2020-12-17T11:38:12","guid":{"rendered":"https:\/\/www.heibel-unplugged.de\/?p=3907"},"modified":"2022-02-09T10:19:29","modified_gmt":"2022-02-09T09:19:29","slug":"heibel-ticker-leser-fragen-boersenprofi-stephan-heibel-antwortet","status":"publish","type":"post","link":"https:\/\/www.heibel-ticker.de\/blog\/heibel-ticker-leser-fragen-boersenprofi-stephan-heibel-antwortet\/","title":{"rendered":"Heibel-Ticker Leser fragen, B\u00f6rsenprofi Stephan Heibel antwortet"},"content":{"rendered":"\n<p>In meiner neuen Heibel-Ticker Ausgabe <a href=\"https:\/\/www.heibel-ticker.de\/heibel_tickers\/1822\" target=\"_blank\" aria-label=\"20\/50 (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">20\/50<\/a> gibt es eine ganze Reihe von Leserfragen zu den unterschiedlichsten Aktien: Lufthansa, Hugo Boss, Hochtief, Bayer, Aareal Bank, Dr\u00e4gerwerk, Hawesko und Krones werden kurz eingeordnet. Der harte Brexit, der von Boris Johnson als &#8222;sehr sehr&#8220; wahrscheinlich bezeichnet wird, k\u00f6nnte eine Korrektur ausl\u00f6sen, meinte ein Leser bereits am Anfang letzter Woche. Und ein anderer wollte sich mit inversen ETFs dagegen absichern. Meine Antworten dazu lesen Sie in Kapitel 05.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Lufthansa, Hugo Boss, Hochtief, Bayer, Aareal Bank &#8211; Was halten Sie von diesen Werten?<\/li><li>Harter Brexit als Ausl\u00f6ser einer Korrektur &#8211; Glauben Sie, dass ein no Deal dem Dax 1.000 Punkte kosten kann?<\/li><li>Dr\u00e4gerwerk, Hawesko, Krones &#8211; Aussitzen oder verkaufen? Gewinn mitnehmen? Weiter halten?<\/li><li>Ausl\u00e4ndische Dividendentitel &#8211; Warum schafft es bei Ihnen keine Aktie aus dem Tabak Umfeld ins Portfolio?<\/li><li>Inverse ETFs zur Absicherung gegen fallende Kurse &#8211; Was halten Sie von einem inversen ETF bzw. ETN auf Nasdaq 100?<\/li><\/ul>\n\n\n\n<p>Weiter zu den ausf\u00fchrlichen Fragen und meinen detaillierten Antworten in Kapitel 05 -> <a aria-label=\" (opens in a new tab)\" href=\"https:\/\/www.heibel-ticker.de\/heibel_tickers\/1822#ch05\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"rank-math-link\">https:\/\/www.heibel-ticker.de\/heibel_tickers\/1822#ch05<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<form class=\"new_abo\" style=\"margin: 0px;\" action=\"https:\/\/www.heibel-ticker.de\/abo\" method=\"post\">\n<h2 class=\"sgny-widget-title\"><font color=\"blue\">\u00dcber 25.000 Leser vertrauen dem Heibel-Ticker<\/font><\/h2>\n<br \/>\n<div class=\"mc4wp-form-fields\">Seit 1998 verfolge ich begeistert die B\u00f6rsen der USA und Europas. Mittlerweile schreibe ich w\u00f6chentlich f\u00fcr mehr als 25.000 Leser \u00fcber Hintergr\u00fcnde zum Aktienmarkt und Ursachen f\u00fcr Kursbewegungen von Aktien.<br \/>\n<br \/>\nMeine Leser sch\u00e4tzen meine neutrale, vereinfachende und unterhaltsame Art. Als Privatanleger nutzen sie meine Einsch\u00e4tzungen und Investmentideen zur selbstst\u00e4ndigen Portfolio-Optimierung.<br \/>\n<br \/>\nSie k\u00f6nnen sich zum <a href=\"https:\/\/www.heibel-ticker.de\/empfehlung?id=40&amp;refID=9\">Heibel-Ticker B\u00f6rsenbrief<\/a> gratis anmelden und erhalten jeden Freitag die neue Ausgabe direkt in Ihr Mail-Postfach.<br \/>\n<br \/>\nKein Spam, kein Abo, Abmeldung jederzeit m\u00f6glich.\n<\/div><br \/>\n<input name=\"refID\" type=\"hidden\" value=\"9\"\/>\n<input name=\"abo[subscribe]\" type=\"hidden\" value=\"subscribe\"\/><input id=\"input_email\" class=\"input_s\" name=\"abo[email]\" size=\"8\" type=\"text\" value=\"\" placeholder=\"E-Mail\"\/><br \/>\n<br \/>\n<input name=\"dsa\" required=\"\" type=\"checkbox\"\/> Ja, ich stimme der <a href=\"https:\/\/www.heibel-ticker.de\/static\/privacy\" target=\"_blank\" rel=\"noopener\">Datenschutzerkl\u00e4rung<\/a> des Heibel-Ticker B\u00f6rsenbriefes zu.<br \/>\n<br \/>\n<input class=\"sgny-readmore-btn send-btn\" name=\"sent2\" type=\"submit\" value=\"Kostenlos anmelden\"\/>\n<p class=\"info-txt\"><\/p>\n<\/form>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In meiner neuen Heibel-Ticker Ausgabe 20\/50 gibt es eine ganze Reihe von Leserfragen zu den unterschiedlichsten Aktien: Lufthansa, Hugo Boss, Hochtief, Bayer, Aareal Bank, Dr\u00e4gerwerk, Hawesko und Krones werden kurz eingeordnet. Der harte Brexit, der von Boris Johnson als &#8222;sehr sehr&#8220; wahrscheinlich bezeichnet wird, k\u00f6nnte eine Korrektur ausl\u00f6sen, meinte ein Leser bereits am Anfang letzter [&hellip;]<\/p>\n","protected":false},"author":7675,"featured_media":3909,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-markteinschatzung"],"_links":{"self":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/users\/7675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/comments?post=3907"}],"version-history":[{"count":1,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3907\/revisions"}],"predecessor-version":[{"id":3908,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3907\/revisions\/3908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media\/3909"}],"wp:attachment":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media?parent=3907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/categories?post=3907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/tags?post=3907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}