{"id":3957,"date":"2021-01-13T14:18:12","date_gmt":"2021-01-13T13:18:12","guid":{"rendered":"https:\/\/www.heibel-unplugged.de\/?p=3957"},"modified":"2025-08-21T10:41:06","modified_gmt":"2025-08-21T08:41:06","slug":"boersen-ausblick-die-gesunde-mischung-einer-fussballmannschaft","status":"publish","type":"post","link":"https:\/\/www.heibel-ticker.de\/blog\/boersen-ausblick-die-gesunde-mischung-einer-fussballmannschaft\/","title":{"rendered":"B\u00f6rsen Ausblick \u2022 Die gesunde Mischung einer Fu\u00dfballmannschaft"},"content":{"rendered":"\n<p>Im neuen Kapitel 04 gehe ich auf unser aktuelles Heibel-Ticker Portfolio ein: Ein diversifiziertes Portfolio ist mit einer gut zusammengestellten Fu\u00dfballmannschaft zu vergleichen: Cash im Tor l\u00e4sst keinen Ball durch, <a href=\"https:\/\/www.heibel-ticker.de\/blog\/gold-analyse-und-investmentstrategie\/\">Gold<\/a> und Bitcoin als stabile Innenverteidiger und <a href=\"https:\/\/www.heibel-ticker.de\/blog\/anleihen-privatanleger\/\">Anleihen<\/a> als Au\u00dfenverteidiger. Dividendentitel (Deutsche Post) k\u00f6nnten im defensiven Mittelfeld stehen, Wachstumsaktien (Spotify) hingegen sind offensiver ausgerichtet. Den Lewandowski als Knipser stellt am besten ein junger Highflyer wie Marvell dar. Und je nach Spielverlauf gibt es alternative Aktien auf der Auswechselbank, die man jederzeit ins Spiel bringen kann.<\/p>\n\n\n\n<p>Sie sehen hier Ausz\u00fcge vom HT+ Kapitel 04. Aus Gr\u00fcnden der Fairness ist das komplette Kapitel mit konkreten Aktien und Empfehlungen Heibel-Ticker PLUS Lesern vorbehalten. Bei Interesse k\u00f6nnen Sie einmalige Heibel-Ticker Ausgaben f\u00fcr 5 Euro beim BoersenKiosk einsehen. Weitere Infos dazu finden Sie unten.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201eIch habe unser Portfolio zum Jahreswechsel wieder auf 100.000 Euro gestellt: Die Anteile der jeweiligen Positionen am Gesamtportfolio habe ich unver\u00e4ndert gelassen und jede Position entsprechend angepasst. Wir starten also mit weiterhin 4,5% Cash, was ich als sehr niedrig empfinde. Aber in den vergangenen Wochen hat es sich gelohnt, so stark investiert zu sein. Stand heute (Freitag, 8. Januar) m\u00f6chte ich nur ein ganz bisschen Gewinne mitnehmen, um im Falle einer Konsolidierung oder Korrektur handlungsf\u00e4hig zu sein. Grunds\u00e4tzlich denke ich aber, dass die Rallye noch einige Wochen weitergeht, und dass der DAX noch deutlich h\u00f6her steigen kann, bevor ein b\u00f6ses Erwachen folgt.<br \/><br \/>Sei&#8217;s drum, wir werden Anfang n\u00e4chster Woche (Montag 11. Januar) ein wenig Cash generieren. Grunds\u00e4tzlich f\u00fchle ich mich weiterhin recht wohl mit unserer Aktienauswahl. Wir haben zu viele Wachstumspositionen, da muss ich mich von der einen oder anderen Position trennen. Doch ich w\u00fcsste nicht, auf welche Position wir verzichten sollen. Alle acht Werte sind bestens positioniert, um im Jahr 2021 entweder weiterzulaufen oder aber erst richtig durchzustarten.<br \/><br \/>Dividendentitel k\u00f6nnten, wie im Jahresausblick gesagt, zu einem \u00dcberraschungssieger im Jahr 2021 werden. Die hat niemand auf dem Zettel und nach den schmerzhaften Erfahrungen der gestrichenen Dividenden im Coronajahr haben viele Anleger diesem Bereich den R\u00fccken zugekehrt.<br \/><br \/>Die beiden Anleihen bleiben vorerst im Portfolio. Der Bitcoin w\u00fcrde in den Bereich der Absicherung gut passen &#8211; wenngleich die Kursschwankungen das nicht vermuten lassen. Doch es ist der Bereich, mit dem wir uns gegen Finanzmarktturbulenzen absichern &#8211; und da ist die Kryptow\u00e4hrung, die weder von Notenbanken, noch von der Politik beeinflusst werden kann, eine sichere Bank.<br \/><br \/>Oder dr\u00fccken wir es doch einmal anders aus: W\u00e4re unser Heibel-Ticker Portfolio eine Fu\u00dfballmannschaft, dann&#8230;\u201c<\/p><\/blockquote>\n\n\n\n<p>Das vollst\u00e4ndige Kapitel 04 finden Sie im PLUS-Bereich unter <a href=\"https:\/\/www.heibel-ticker.de\/empfehlung?id=40&amp;refID=9&amp;target=heibel_tickers\/1828&amp;anchor=ch04\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">https:\/\/www.heibel-ticker.de\/1828&amp;anchor=ch04<\/a> oder Sie finden es in der einzelnen Ausgabe beim B\u00f6rsenkiosk unter <a href=\"https:\/\/boersenkiosk.de\/Details.php?prod_id=184\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener nofollow\" class=\"rank-math-link\">https:\/\/boersenkiosk.de\/Details.php?prod_id=184<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im neuen Kapitel 04 gehe ich auf unser aktuelles Heibel-Ticker Portfolio ein: Ein diversifiziertes Portfolio ist mit einer gut zusammengestellten Fu\u00dfballmannschaft zu vergleichen: Cash im Tor l\u00e4sst keinen Ball durch, Gold und Bitcoin als stabile Innenverteidiger und Anleihen als Au\u00dfenverteidiger. Dividendentitel (Deutsche Post) k\u00f6nnten im defensiven Mittelfeld stehen, Wachstumsaktien (Spotify) hingegen sind offensiver ausgerichtet. Den [&hellip;]<\/p>\n","protected":false},"author":7675,"featured_media":3958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-markteinschatzung"],"_links":{"self":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/users\/7675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/comments?post=3957"}],"version-history":[{"count":3,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3957\/revisions"}],"predecessor-version":[{"id":3961,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/3957\/revisions\/3961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media\/3958"}],"wp:attachment":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media?parent=3957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/categories?post=3957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/tags?post=3957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}