{"id":4916,"date":"2020-09-15T10:46:00","date_gmt":"2020-09-15T08:46:00","guid":{"rendered":"https:\/\/www.heibel-unplugged.de\/?p=4916"},"modified":"2025-08-21T10:41:06","modified_gmt":"2025-08-21T08:41:06","slug":"antizyklischer-boersenbrief-und-antizyklische-aktien","status":"publish","type":"post","link":"https:\/\/www.heibel-ticker.de\/blog\/antizyklischer-boersenbrief-und-antizyklische-aktien\/","title":{"rendered":"Antizyklischer B\u00f6rsenbrief und antizyklische Aktien"},"content":{"rendered":"\n<p>Je nach Konjunkturphase und Stimmung unter den Anlegern investieren wir im Heibel-Ticker auch in antizyklische Aktien. Dadurch ist der Heibel-Ticker B\u00f6rsenbrief auch ein antizyklischer B\u00f6rsenbrief.<\/p>\n\n\n\n<p>Langfristig orientierte Anleger investieren gerne antizyklisch. Wenn die Stimmung an der B\u00f6rse am Tiefpunkt ist, werden Aktien gekauft und wenn Euphorie herrscht, wird zu hohen Aktienkursen verkauft. Ganz grob gesagt kann man damit zu niedrigen Preisen einsteigen und bei hohen Kursen mit beachtlichem Gewinn aussteigen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Antizyklisch Investieren<\/h2>\n\n\n\n<p>Der zeitliche Rahmen der antizyklischen Entwicklungen kann sich auf Aktien, Branchen, M\u00e4rkte oder ganze Gesellschaften beziehen. Ein noch recht aktuelles Beispiel ist der Coronacrash im M\u00e4rz 2020 und die anschlie\u00dfende Rallye an den Aktienm\u00e4rkten. Wer im Tief des Coronacrash antizyklisch &#8211; entgegen der schlechten B\u00f6rsenstimmung &#8211; investiert hat, durfte sich anschlie\u00dfend \u00fcber satte Gewinne freuen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.heibel-unplugged.de\/wp-content\/uploads\/2021\/09\/Antizyklischer-Boersenbrief-und-antizyklische-Aktien.jpg\" alt=\"Antizyklischer B\u00f6rsenbrief und antizyklische Aktien\" class=\"wp-image-4923\" width=\"520\" height=\"392\" title=\"\" srcset=\"https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/09\/Antizyklischer-Boersenbrief-und-antizyklische-Aktien.jpg 444w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/09\/Antizyklischer-Boersenbrief-und-antizyklische-Aktien-300x226.jpg 300w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/09\/Antizyklischer-Boersenbrief-und-antizyklische-Aktien-150x113.jpg 150w\" sizes=\"(max-width: 520px) 100vw, 520px\" \/><figcaption class=\"wp-element-caption\">Darstellung zum antizyklischen Investieren<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ein etwas \u00e4lteres Beispiel, was mit der Geburt des Heibel-Ticker zusammenl\u00e4uft, ist die Internetblase 2000. Ich habe meinen Lesern damals Ende 1999 den Verkauf von Aktien empfohlen, entgegen der herrschenden Euphorie an den Aktienm\u00e4rkten &#8211; auch eine antizyklische Empfehlung. Wer sich damals vor dem Crash von einem Teil seiner Aktien getrennt hatte, konnte seine bisherigen Gewinne sichern und (wieder antizyklisch) ins anschlie\u00dfende Tief investieren und vom Wiederanstieg profitieren.<\/p>\n\n\n\n<p>Auch ohne Crashs kann man antizyklisch investieren: bei Aktien nehmen die B\u00f6rsen die Entwicklungen der Real-Wirtschaft im Durchschnitt 6 bis 9 Monate vorweg. Oft werden nach guten Quartalsberichten Aktien kurzzeitig ausverkauft. Vermeldet ein Aktienunternehmen bei Quartalsberichten gute Zahlen, so kann man davon ausgehen, dass der Aktienkurs den dazugeh\u00f6rigen Anstieg bereits hinter sich hat. &#8222;Sell the news&#8220; passt hier als Zitat f\u00fcr antizyklisches Investieren vor der Bekanntgabe der Ergebnisse. Im Anschluss an den Ausverkauf steigen die Aktien meist wieder auf ihr vorheriges Niveau und meistens noch weiter. Mit diesem Wissen kann man erfolgreich antizyklisch Aktien kaufen und verkaufen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Antizyklische Aktien<\/h2>\n\n\n\n<p>Es gibt auch antizyklische Aktien, besser gesagt saisonal abh\u00e4ngige Aktien. Zum Beispiel braucht man Streusalz im Winter oder Getreideernten sind zu warmen Jahreszeiten relevant. Auch k\u00f6nnen <a href=\"https:\/\/www.heibel-ticker.de\/blog\/gold-analyse-und-investmentstrategie\/\">Gold<\/a> oder \u00d6l entgegen bzw. antizyklisch zu wirtschaftlichen und gesellschaftlichen Entwicklungen verlaufen.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"800\" height=\"149\" src=\"https:\/\/www.heibel-unplugged.de\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-800x149.png\" alt=\"Heibel-Ticker Logo\" class=\"wp-image-4751\" title=\"\" srcset=\"https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-800x149.png 800w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-300x56.png 300w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-150x28.png 150w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-768x143.png 768w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-1536x286.png 1536w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Heibel-Ticker-Logo-komplett-breit-durchsichtig-2048x381.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Als antizyklischer B\u00f6rsenbrief<\/h2>\n\n\n\n<p>In meinem Heibel-Ticker B\u00f6rsenbrief ber\u00fccksichtige ich antizyklische Entwicklungen. So erwirtschaften wir f\u00fcr unser Heibel-Ticker Portfolio mit antizyklischen Investitionen immer wieder Gewinne, was wiederrum auch zum Erfolg unseres Musterdepots beitr\u00e4gt.<\/p>\n\n\n\n<p>Unser Heibel-Ticker Portfolio ist seit seiner Einf\u00fchrung in 2008 um \u00fcber 325% angewachsen (Stand Mitte 2021), dies entspricht j\u00e4hrlich +11%.<\/p>\n\n\n\n<p>Mit dem Heibel-Ticker Portfolio h\u00e4tten Sie von 2008 bis Mitte 2021 in 13 Jahren aus 100.000 Euro 425.000 Euro gemacht, durchschnittlich 11% pro Jahr. Der DAX als Vergleich hat 5% pro Jahr in dem Zeitraum erzielt, aus 100.000 Euro wurden nur 196.000 Euro.<\/p>\n\n\n\n<p>Um als antizyklischer <a href=\"https:\/\/www.heibel-ticker.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">B\u00f6rsenbrief<\/a> erfolgreich zu sein, ben\u00f6tigt es eine gewisse Erfahrung. Diese gebe ich gerne meinen Lesern weiter. F\u00fcr mich ist es wichtig, dass meine Leser die Hintergr\u00fcnde der Finanzwelt verstehen und ihr Portfolio erfolgreich ausrichten. Das machen meine Leser mit meinen Einsch\u00e4tzungen und Empfehlungen in der Regel noch besser als ich mit unserem Heibel-Ticker Portfolio. Ich verfolge einen eher defensiven, daf\u00fcr sicheren Ansatz.<\/p>\n\n\n\n<p>Wenn Sie sich f\u00fcr meinen B\u00f6rsenbrief interessieren, k\u00f6nnen Sie bisherige Ausgaben durchst\u00f6bern oder sich kostenlos f\u00fcr die Heibel-Ticker Free Version anmelden. Bisherige Ausgaben, die kostenlose Anmeldung sowie Informationen zur PLUS Variante mit mehr Inhalten und Funktionen k\u00f6nnen Sie unter <a href=\"http:\/\/heibel-ticker.de\" target=\"_blank\" rel=\"noreferrer noopener\">heibel-ticker.de<\/a> <\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\">(noch als Ref Link mit HU als Lieferant einrichten) finden. <\/mark><\/p>\n\n\n\n<p>take share, Ihr B\u00f6rsenschreibel Stephan Heibel<\/p>\n\n\n\n<p>Chefredakteur und Herausgeber des Heibel-Ticker B\u00f6rsenbriefs<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"270\" height=\"300\" src=\"https:\/\/www.heibel-unplugged.de\/wp-content\/uploads\/2021\/08\/Stephan-Heibel-Herausgeber-und-Chefredakteur-des-Heibel-Ticker-Boersenbrief.jpg\" alt=\"Stephan Heibel, Chefredakteur und Herausgeber des Heibel-Ticker B\u00f6rsenbriefs\" class=\"wp-image-4712\" title=\"\" srcset=\"https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Stephan-Heibel-Herausgeber-und-Chefredakteur-des-Heibel-Ticker-Boersenbrief.jpg 270w, https:\/\/www.heibel-ticker.de\/blog\/wp-content\/uploads\/2021\/08\/Stephan-Heibel-Herausgeber-und-Chefredakteur-des-Heibel-Ticker-Boersenbrief-135x150.jpg 135w\" sizes=\"(max-width: 270px) 100vw, 270px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Erfahrung mit antizyklischem Heibel-Ticker B\u00f6rsenbrief<\/h2>\n\n\n\n<p>Hier k\u00f6nnen Sie \u00fcber Erfahrung von Lesern mit dem Heibel-Ticker B\u00f6rsenbrief lesen: <a href=\"https:\/\/www.heibel-unplugged.de\/heibel-ticker-erfahrungen\/\" data-type=\"URL\" data-id=\"https:\/\/www.heibel-unplugged.de\/heibel-ticker-erfahrungen\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.heibel-unplugged.de\/heibel-ticker-erfahrungen\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je nach Konjunkturphase und Stimmung unter den Anlegern investieren wir im Heibel-Ticker auch in antizyklische Aktien. Dadurch ist der Heibel-Ticker B\u00f6rsenbrief auch ein antizyklischer B\u00f6rsenbrief. Langfristig orientierte Anleger investieren gerne antizyklisch. Wenn die Stimmung an der B\u00f6rse am Tiefpunkt ist, werden Aktien gekauft und wenn Euphorie herrscht, wird zu hohen Aktienkursen verkauft. Ganz grob gesagt [&hellip;]<\/p>\n","protected":false},"author":7675,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4916","post","type-post","status-publish","format-standard","hentry","category-markteinschatzung"],"_links":{"self":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/4916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/users\/7675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/comments?post=4916"}],"version-history":[{"count":21,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/4916\/revisions"}],"predecessor-version":[{"id":6862,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/4916\/revisions\/6862"}],"wp:attachment":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media?parent=4916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/categories?post=4916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/tags?post=4916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}