{"id":84,"date":"2007-02-20T09:52:13","date_gmt":"2007-02-20T08:52:13","guid":{"rendered":"http:\/\/www.heibel-unplugged.de\/84,boersenanalyse-dax-und-oel\/"},"modified":"2022-02-09T10:17:04","modified_gmt":"2022-02-09T09:17:04","slug":"boersenanalyse-dax-und-oel","status":"publish","type":"post","link":"https:\/\/www.heibel-ticker.de\/blog\/boersenanalyse-dax-und-oel\/","title":{"rendered":"B\u00f6rsenanalyse: DAX und \u00d6L"},"content":{"rendered":"<p>Sehr geehrter Herr Heibel,<\/p>\n<p>bin ja nun einmal gespannt, was nun passiert: Dax &uuml;ber 6900, Oel bei 60 USD und &uuml;berall h&ouml;rt und liest man: Aktien kaufen, noch lange nicht zu teuer- nur positive Sachen&#8230; <\/p>\n<p>Nach Ihrem B&ouml;rsenbrief m&uuml;sste die Korrektur kommen.<\/p>\n<p>Werde dann sofort ihren Ticker abonnieren.<\/p>\n<p>Netten Gru&szlig;, Rainer aus Berlin<\/p>\n<p>ANTWORT:<\/p>\n<p>Vielen Dank f&uuml;r Ihr Schreiben. Wie immer ist die B&ouml;rse auch in diesen Tagen keine Einbahnstra&szlig;e: Obwohl ich langfristig noch sehr optimistisch bin (DAX-KGV von 13 ist historisch gesehen sehr g&uuml;nstig), bef&uuml;rchte ich kurzfristig eine Korrektur. Die Korrektur sollte aber wesentlich moderater ausfallen, als letztes Fr&uuml;hjahr, da kaum eine &Uuml;berhitzung an den Aktienm&auml;rkten festzustellen ist. Also w&uuml;rde ich derzeit Korrekturphasen von wenigen Tagen bereits nutzen, um zu Kaufen. <\/p>\n<p>In Zahlen: Ich wei&szlig; nicht, wann die Korrektur beginnt, ich gebe ihr aber ein Potential von 10 %. Vom aktuellen Niveau also sollte der Dax dann in Richtung 6.300 Punkte rauschen. <\/p>\n<p>Das &Ouml;l wird vorerst nicht mehr unter 60 USD rutschen, dort ist die Luft raus. Aber auch ein schneller Anstieg &uuml;ber 70 USD wird nicht geschehen, es sei denn, das Waffengerassel der USA mit dem Iran oder eine &auml;hnliche politische Zuspitzung w&uuml;rde f&uuml;r Unruhe sorgen. <\/p>\n<p>Ich habe Ihnen die aktuelle Ausgabe von diesem Wochenende an die E-Mail angehangen. Dort bin ich auf genau diese Erwartungen genauer eingegangen. Es w&uuml;rde mich freuen, Sie wieder als Kunden gewinnen zu k&ouml;nnen. Vielen Dank f&uuml;r Ihr Interesse an meinem B&ouml;rsenbrief <span lang=\"EN-US\" style=\"font-size: 10pt; font-family: &quot;Courier New&quot;;\"><\/span><a href=\"http:\/\/www.heibel-ticker.de\/empfehlung.php?id=40&amp;refID=9\">Heibel-Ticker PLUS<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sehr geehrter Herr Heibel, bin ja nun einmal gespannt, was nun passiert: Dax &uuml;ber 6900, Oel bei 60 USD und &uuml;berall h&ouml;rt und liest man: Aktien kaufen, noch lange nicht zu teuer- nur positive Sachen&#8230; Nach Ihrem B&ouml;rsenbrief m&uuml;sste die Korrektur kommen. Werde dann sofort ihren Ticker abonnieren. Netten Gru&szlig;, Rainer aus Berlin ANTWORT: Vielen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[147],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-leserfragen","tag-boersenanalyse-boersenbrief-boersenkurse-boerse-aktuell"],"_links":{"self":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":1,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"predecessor-version":[{"id":5673,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/posts\/84\/revisions\/5673"}],"wp:attachment":[{"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heibel-ticker.de\/blog\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}